{"id":250051,"date":"2024-01-04T18:49:51","date_gmt":"2024-01-04T17:49:51","guid":{"rendered":"https:\/\/vereinfair.ch\/?page_id=250051"},"modified":"2024-05-28T21:22:56","modified_gmt":"2024-05-28T19:22:56","slug":"premio","status":"publish","type":"page","link":"https:\/\/vereinfair.ch\/it\/auszeichnungen\/","title":{"rendered":"Premi e onorificenze"},"content":{"rendered":"\n[et_pb_section fb_built=&#187;1&#8243; _builder_version=&#187;4.23.4&#8243; _module_preset=&#187;b2bd591a-8e13-40ac-8455-5c7fcc06917f&#187; background_image=&#187;https:\/\/vereinfair.ch\/wp-content\/uploads\/2022\/11\/Verein_FAIR_Sanitas_Challenge_Preis_3.jpg&#187; background_position=&#187;top_center&#187; da_disable_devices=&#187;off|off|off&#187; locked=&#187;off&#187; global_colors_info=&#187;{}&#187; da_is_popup=&#187;off&#187; da_exit_intent=&#187;off&#187; da_has_close=&#187;on&#187; da_alt_close=&#187;off&#187; da_dark_close=&#187;off&#187; da_not_modal=&#187;on&#187; da_is_singular=&#187;off&#187; da_with_loader=&#187;off&#187; da_has_shadow=&#187;on&#187;][et_pb_row _builder_version=&#187;4.23.1&#8243; _module_preset=&#187;default&#187; width_tablet=&#187;&#187; width_phone=&#187;90%&#187; width_last_edited=&#187;on|phone&#187; max_width_tablet=&#187;&#187; max_width_phone=&#187;100%&#187; max_width_last_edited=&#187;on|phone&#187; global_colors_info=&#187;{}&#187;][et_pb_column type=&#187;4_4&#8243; _builder_version=&#187;4.23.1&#8243; _module_preset=&#187;default&#187; global_colors_info=&#187;{}&#187;][et_pb_text _builder_version=&#187;4.24.2&#8243; _module_preset=&#187;default&#187; text_text_color=&#187;#FFFFFF&#187; header_text_color=&#187;#E1CDB9&#8243; header_font_size=&#187;100px&#187; header_4_text_color=&#187;#F9F9F9&#8243; header_6_text_color=&#187;#F9F9F9&#8243; text_orientation=&#187;center&#187; header_font_size_tablet=&#187;80px&#187; header_font_size_phone=&#187;40px&#187; header_font_size_last_edited=&#187;on|phone&#187; header_6_font_size_tablet=&#187;&#187; header_6_font_size_phone=&#187;16px&#187; header_6_font_size_last_edited=&#187;on|phone&#187; global_colors_info=&#187;{}&#187;]<h1>Preisgekr\u00f6nte Arbeit<\/h1>\n<p><strong>Auszeichnungen, die wir f\u00fcr unsere Engagements erhalten haben<\/strong><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#187;1&#8243; _builder_version=&#187;4.23.4&#8243; _module_preset=&#187;ee32ece3-fb5d-430a-a437-03c296a2e57f&#187; da_disable_devices=&#187;off|off|off&#187; global_colors_info=&#187;{}&#187; da_is_popup=&#187;off&#187; da_exit_intent=&#187;off&#187; da_has_close=&#187;on&#187; da_alt_close=&#187;off&#187; da_dark_close=&#187;off&#187; da_not_modal=&#187;on&#187; da_is_singular=&#187;off&#187; da_with_loader=&#187;off&#187; da_has_shadow=&#187;on&#187;][et_pb_row column_structure=&#187;3_5,2_5&#8243; _builder_version=&#187;4.23.2&#8243; _module_preset=&#187;default&#187; custom_padding=&#187;||7%||false|false&#187; global_colors_info=&#187;{}&#187;][et_pb_column type=&#187;3_5&#8243; _builder_version=&#187;4.23.1&#8243; _module_preset=&#187;default&#187; global_colors_info=&#187;{}&#187;][et_pb_text content_tablet=&#187;<h2 style=%22text-align: left;%22>Auszeich-<br \/>nungen<\/h2>&#187; content_phone=&#187;<h2 style=%22text-align: left;%22>Auszeich-\nnungen<\/h2>&#187; content_last_edited=&#187;on|phone&#187; _builder_version=&#187;4.24.2&#8243; _module_preset=&#187;40ff44a4-7e2c-488f-9b7f-0d45869b47d0&#8243; header_text_align=&#187;center&#187; header_text_color=&#187;#1F353E&#187; transform_translate_linked__hover=&#187;off&#187; width=&#187;96.8%&#187; module_alignment=&#187;left&#187; custom_margin=&#187;||||false|false&#187; locked=&#187;off&#187; global_colors_info=&#187;{}&#187; transform_styles__hover_enabled=&#187;on|hover&#187; transform_scale__hover_enabled=&#187;on|hover&#187; transform_translate__hover_enabled=&#187;on|desktop&#187; transform_rotate__hover_enabled=&#187;on|desktop&#187; transform_skew__hover_enabled=&#187;on|desktop&#187; transform_origin__hover_enabled=&#187;on|desktop&#187; transform_translate__hover=&#187;4px|0px&#187;]<h2 style=\"text-align: left;\">Auszeich-<br \/>nungen<\/h2>[\/et_pb_text][et_pb_text _builder_version=&#187;4.23.4&#8243; _module_preset=&#187;default&#187; text_font=&#187;|300|||||||&#187; global_colors_info=&#187;{}&#187;]<p>Der Verein FAIR! wurde bereits mehrmals f\u00fcr sein ausserordentliches Engagement ausgezeichnet. Diese Auszeichnungen waren extrem vielf\u00e4ltig und widerspiegeln somit auch unsere breit abgest\u00fctzte Arbeit. <\/p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#187;2_5&#8243; _builder_version=&#187;4.23.1&#8243; _module_preset=&#187;default&#187; global_colors_info=&#187;{}&#187;][et_pb_image src=&#187;https:\/\/vereinfair.ch\/wp-content\/uploads\/2023\/12\/FAIR_Pikto_Stern.svg&#187; title_text=&#187;FAIR!_Pikto_Stern&#187; align=&#187;center&#187; disabled_on=&#187;on|on|off&#187; _builder_version=&#187;4.24.0&#8243; _module_preset=&#187;default&#187; width=&#187;60%&#187; width_tablet=&#187;60%&#187; width_phone=&#187;60%&#187; width_last_edited=&#187;on|tablet&#187; locked=&#187;off&#187; global_colors_info=&#187;{}&#187;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#187;1&#8243; next_background_color=&#187;#1F353E&#187; _builder_version=&#187;4.24.0&#8243; _module_preset=&#187;ee32ece3-fb5d-430a-a437-03c296a2e57f&#187; custom_padding=&#187;3%||||false|false&#187; bottom_divider_style=&#187;none&#187; da_disable_devices=&#187;off|off|off&#187; locked=&#187;off&#187; global_colors_info=&#187;{}&#187; da_is_popup=&#187;off&#187; da_exit_intent=&#187;off&#187; da_has_close=&#187;on&#187; da_alt_close=&#187;off&#187; da_dark_close=&#187;off&#187; da_not_modal=&#187;on&#187; da_is_singular=&#187;off&#187; da_with_loader=&#187;off&#187; da_has_shadow=&#187;on&#187;][et_pb_row column_structure=&#187;1_2,1_2&#8243; _builder_version=&#187;4.23.2&#8243; _module_preset=&#187;default&#187; global_colors_info=&#187;{}&#187;][et_pb_column type=&#187;1_2&#8243; _builder_version=&#187;4.23.2&#8243; _module_preset=&#187;default&#187; global_colors_info=&#187;{}&#187;][et_pb_blurb title=&#187;Young Caritas Award&#187; image=&#187;https:\/\/vereinfair.ch\/wp-content\/uploads\/2022\/11\/Verein_FAIR_Young_Caritas_Award.jpg&#187; alt=&#187;Verein_FAIR_Young_Caritas_Award&#187; _builder_version=&#187;4.25.0&#8243; _module_preset=&#187;_initial&#187; body_font=&#187;|300|||||||&#187; hover_enabled=&#187;0&#8243; border_radii_image=&#187;on|5px|5px|5px|5px&#187; global_colors_info=&#187;{}&#187; sticky_enabled=&#187;0&#8243;]<p>F\u00fcr das Projekt <a href=\"https:\/\/www.hauspourbienne.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Haus pour Bienne<\/strong><\/a> waren wir mit Stand up for refugees und zahlreichen Freiwilligen f\u00fcr den youngCaritas Award 2017 nominiert. Am Schluss gabs den grossartigen 5. Rang von knapp 20 nominierten Projekten. Wir freuen uns \u00fcber diese neuste Auszeichnung.<\/p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#187;1_2&#8243; _builder_version=&#187;4.23.2&#8243; _module_preset=&#187;default&#187; global_colors_info=&#187;{}&#187;][et_pb_blurb title=&#187;Sanitas Challenge Pres&#187; image=&#187;https:\/\/vereinfair.ch\/wp-content\/uploads\/2022\/11\/Verein_FAIR_Sanitas_Challenge_Preis.jpg&#187; alt=&#187;Verein_FAIR_Young_Caritas_Award&#187; _builder_version=&#187;4.23.4&#8243; _module_preset=&#187;_initial&#187; body_font=&#187;|300|||||||&#187; hover_enabled=&#187;0&#8243; border_radii_image=&#187;on|5px|5px|5px|5px&#187; global_colors_info=&#187;{}&#187;]<p>Das Projekt <strong><a href=\"https:\/\/vereinfair.ch\/projekte\/biel-tanzt\/\">Biel Tanzt<\/a><\/strong> gewinnt die Sanitas Challenge in der Region Bern und belegt den 3. Platz im nationalen Vergleich! \u201eDie Jury honoriert, dass auf eine niederschwellige Art viele Menschen zu Bewegung animiert werden. Das Projekt ist ein T\u00fcr\u00f6ffner zu sportlicher Bet\u00e4tigung und ein Eisbrecher zu sozialen Kontakten und gelebter Toleranz.\u201c<\/p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#187;1_2,1_2&#8243; _builder_version=&#187;4.23.2&#8243; _module_preset=&#187;default&#187; global_colors_info=&#187;{}&#187;][et_pb_column type=&#187;1_2&#8243; _builder_version=&#187;4.23.2&#8243; _module_preset=&#187;default&#187; global_colors_info=&#187;{}&#187;][et_pb_blurb title=&#187;Ecosport.ch Award&#187; image=&#187;https:\/\/vereinfair.ch\/wp-content\/uploads\/2022\/11\/Verein_FAIR_Fairtrade_Swiss_Olympic_Ecosport_Award.jpg&#187; alt=&#187;Verein_FAIR_Young_Caritas_Award&#187; _builder_version=&#187;4.23.4&#8243; _module_preset=&#187;_initial&#187; body_font=&#187;|300|||||||&#187; hover_enabled=&#187;0&#8243; border_radii_image=&#187;on|5px|5px|5px|5px&#187; global_colors_info=&#187;{}&#187;]<p>Der Event X-DAYS 2012 gewinnt den Ecosport.ch-Award 2012 von <a href=\"https:\/\/www.swissolympic.ch\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Swiss Olympic<\/a>. Der Verein FAIR! war Nachhaltigkeitspartner und hat aktiv mitgeholfen, den Preis nach Biel zu holen. Mit verschiedensten Massnahmen (\u00d6kostrom, Abfalltrennung, Sensibilisierung, nachhaltiges Food-Angebot und mehr) wurden in Zusammenarbeit mit dem Verein X-DAYS nachhaltige Jugendkultur- und Sporttage auf die Beine gestellt.<\/p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#187;1_2&#8243; _builder_version=&#187;4.23.2&#8243; _module_preset=&#187;default&#187; global_colors_info=&#187;{}&#187;][et_pb_blurb title=&#187;BAR.&#187; image=&#187;https:\/\/vereinfair.ch\/wp-content\/uploads\/2022\/10\/Verein_FAIR_Fairtrade_Award2012.jpg&#187; alt=&#187;Verein_FAIR_Young_Caritas_Award&#187; _builder_version=&#187;4.23.4&#8243; _module_preset=&#187;_initial&#187; body_font=&#187;|300|||||||&#187; hover_enabled=&#187;0&#8243; border_radii_image=&#187;on|5px|5px|5px|5px&#187; global_colors_info=&#187;{}&#187;]<p>Der Verein FAIR! gewann f\u00fcr das Projekt <a href=\"https:\/\/barparlapapp.ch\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">BAR.<\/a> in Kombination mit dem Engagement des Vereins f\u00fcr den fairen Handel den Fairtrade Award anl\u00e4sslich des 20-j\u00e4hrigen Jubil\u00e4ums von Max Havelaar. Unser erster Award der Vereinsgeschichte!<\/p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Preisgekr\u00f6nte Arbeit Auszeichnungen, die wir f\u00fcr unsere Engagements erhalten habenAuszeich-nungenDer Verein FAIR! wurde bereits mehrmals f\u00fcr sein ausserordentliches Engagement ausgezeichnet. Diese Auszeichnungen waren extrem vielf\u00e4ltig und widerspiegeln somit auch unsere breit abgest\u00fctzte Arbeit. F\u00fcr das Projekt Haus pour Bienne waren wir mit Stand up for refugees und zahlreichen Freiwilligen f\u00fcr den youngCaritas Award 2017 nominiert. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-250051","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/vereinfair.ch\/it\/wp-json\/wp\/v2\/pages\/250051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vereinfair.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vereinfair.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vereinfair.ch\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vereinfair.ch\/it\/wp-json\/wp\/v2\/comments?post=250051"}],"version-history":[{"count":8,"href":"https:\/\/vereinfair.ch\/it\/wp-json\/wp\/v2\/pages\/250051\/revisions"}],"predecessor-version":[{"id":253454,"href":"https:\/\/vereinfair.ch\/it\/wp-json\/wp\/v2\/pages\/250051\/revisions\/253454"}],"wp:attachment":[{"href":"https:\/\/vereinfair.ch\/it\/wp-json\/wp\/v2\/media?parent=250051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}